{"id":737,"date":"2018-01-09T18:11:48","date_gmt":"2018-01-09T17:11:48","guid":{"rendered":"http:\/\/larcade.ch\/larcadewp2\/?p=737"},"modified":"2018-01-11T18:17:24","modified_gmt":"2018-01-11T17:17:24","slug":"swisscom-panne-telephonie","status":"publish","type":"post","link":"http:\/\/larcade.ch\/larcadewp2\/2018\/01\/09\/swisscom-panne-telephonie\/","title":{"rendered":"Swisscom panne t\u00e9l\u00e9phonie"},"content":{"rendered":"<p><span style=\"color: #000000; font-family: Trebuchet MS; font-size: small;\">Depuis lundi 8 janvier 2018 \u00e0 10h38, les communications entrantes et sortantes des clients commerciaux qui disposent du service Smart Business Connect connaissent des perturbations. Nos sp\u00e9cialistes sont parvenus \u00e0 identifier la cause tard dans la soir\u00e9e de mardi et ont pris des mesures de stabilisation dans la nuit de mardi \u00e0 mercredi. Nos sp\u00e9cialistes travaillent en collaboration avec le fournisseur de logiciel en service par roulement \u00e0 la r\u00e9paration des probl\u00e8mes \u2013 d&rsquo;autres mesures sont en train d&rsquo;\u00eatre mises en \u0153uvre actuellement. \u00c0 l\u2019heure actuelle, nous ne pouvons pas exclure que d\u2019autres probl\u00e8mes se produisent. Nous surveillons donc tr\u00e8s attentivement nos syst\u00e8mes. Nous vous informerons des \u00e9tapes suivantes.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Trebuchet MS; font-size: small;\">Nous nous excusons pour les restrictions qu&rsquo;a subi le service. Nous regrettons les d\u00e9sagr\u00e9ments qui ont \u00e9t\u00e9 caus\u00e9s pour vous et vos collaborateurs. Swisscom est conscient que la t\u00e9l\u00e9phonie est un composant important de ses activit\u00e9s commerciales et l&rsquo;entreprise met tout en \u0153uvre pour r\u00e9tablir le plus rapidement possible une exploitation stable.<\/span><\/p>\n<p><span style=\"color: #000000; font-family: Trebuchet MS; font-size: small;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-738\" src=\"http:\/\/larcade.ch\/larcadewp2\/wp-content\/uploads\/2018\/01\/swisscom.png\" alt=\"\" width=\"39\" height=\"39\" \/><span style=\"color: #3366ff; font-size: 18pt;\">SWISSCOM<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis lundi 8 janvier 2018 \u00e0 10h38, les communications entrantes et sortantes des clients commerciaux qui disposent du service Smart Business Connect [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-737","post","type-post","status-publish","format-standard","hentry","category-actualites"],"_links":{"self":[{"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/posts\/737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/comments?post=737"}],"version-history":[{"count":1,"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/posts\/737\/revisions"}],"predecessor-version":[{"id":739,"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/posts\/737\/revisions\/739"}],"wp:attachment":[{"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/media?parent=737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/categories?post=737"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/larcade.ch\/larcadewp2\/wp-json\/wp\/v2\/tags?post=737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}